{"id":46432,"date":"2026-05-01T15:47:45","date_gmt":"2026-05-01T13:47:45","guid":{"rendered":"https:\/\/www.radialtorque.eu\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/"},"modified":"2026-05-01T15:47:45","modified_gmt":"2026-05-01T13:47:45","slug":"torque-tip-de-cecile-la-securite-avant-tout","status":"publish","type":"torquetips","link":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/","title":{"rendered":"Torque Tip de C\u00e9cile &#8211; La s\u00e9curit\u00e9 avant tout"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":40064,"template":"","class_list":["post-46432","torquetips","type-torquetips","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/\" \/>\n<meta property=\"og:site_name\" content=\"Radial Torque Tools B.V.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/01\/TTT-Safety-first.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/\",\"name\":\"Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/TTT-Safety-first.jpg\",\"datePublished\":\"2026-05-01T13:47:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/TTT-Safety-first.jpg\",\"contentUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/TTT-Safety-first.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/torque-tip-de-cecile-la-securite-avant-tout\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torque Tips\",\"item\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/torquetips\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Torque Tip de C\u00e9cile &#8211; La s\u00e9curit\u00e9 avant tout\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/\",\"name\":\"Radial Torque Tools B.V.\",\"description\":\"Radial Torque Tools B.V.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#organization\",\"name\":\"Radial Torque Tools B.V.\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/RADIAL_Logo__DEF.svg\",\"contentUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/RADIAL_Logo__DEF.svg\",\"width\":786,\"height\":208,\"caption\":\"Radial Torque Tools B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/","og_locale":"fr_FR","og_type":"article","og_title":"Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.","og_url":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/","og_site_name":"Radial Torque Tools B.V.","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/01\/TTT-Safety-first.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/","url":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/","name":"Torque Tip de C\u00e9cile - La s\u00e9curit\u00e9 avant tout - Radial Torque Tools B.V.","isPartOf":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/#primaryimage"},"image":{"@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/01\/TTT-Safety-first.jpg","datePublished":"2026-05-01T13:47:45+00:00","breadcrumb":{"@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/#primaryimage","url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/01\/TTT-Safety-first.jpg","contentUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/01\/TTT-Safety-first.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/torque-tip-de-cecile-la-securite-avant-tout\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.radialtorque.eu\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Torque Tips","item":"https:\/\/www.radialtorque.eu\/fr\/torquetips\/"},{"@type":"ListItem","position":3,"name":"Torque Tip de C\u00e9cile &#8211; La s\u00e9curit\u00e9 avant tout"}]},{"@type":"WebSite","@id":"https:\/\/www.radialtorque.eu\/fr\/#website","url":"https:\/\/www.radialtorque.eu\/fr\/","name":"Radial Torque Tools B.V.","description":"Radial Torque Tools B.V.","publisher":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radialtorque.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.radialtorque.eu\/fr\/#organization","name":"Radial Torque Tools B.V.","url":"https:\/\/www.radialtorque.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.radialtorque.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/02\/RADIAL_Logo__DEF.svg","contentUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/02\/RADIAL_Logo__DEF.svg","width":786,"height":208,"caption":"Radial Torque Tools B.V."},"image":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/torquetips\/46432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/torquetips"}],"about":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/types\/torquetips"}],"version-history":[{"count":0,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/torquetips\/46432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/media\/40064"}],"wp:attachment":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/media?parent=46432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}