{"id":9425,"date":"2022-05-12T15:25:48","date_gmt":"2022-05-12T13:25:48","guid":{"rendered":"https:\/\/www.radialtorque.eu\/nouvelles\/"},"modified":"2026-04-28T14:09:28","modified_gmt":"2026-04-28T12:09:28","slug":"actus","status":"publish","type":"page","link":"https:\/\/www.radialtorque.eu\/fr\/actus\/","title":{"rendered":"Nouvelles"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9425\" class=\"elementor elementor-9425 elementor-4441\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1049499 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1049499\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ed8c0cf\" data-id=\"ed8c0cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1095f3d elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"1095f3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/02\/RADIAL_Logo__DEF.svg\" class=\"attachment-large size-large wp-image-2127\" alt=\"Radial Logo\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7096291\" data-id=\"7096291\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-793b783 elementor-widget elementor-widget-spacer\" data-id=\"793b783\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ac78d elementor-widget elementor-widget-jet-mega-menu\" data-id=\"63ac78d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-mega-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-mega-menu jet-mega-menu--layout-horizontal jet-mega-menu--sub-position-right jet-mega-menu--dropdown-layout-default jet-mega-menu--dropdown-position-right jet-mega-menu--animation-none jet-mega-menu--location-elementor    jet-mega-menu--fill-svg-icons\" data-settings='{\"menuId\":\"56\",\"menuUniqId\":\"6a047da8cccd3\",\"rollUp\":false,\"megaAjaxLoad\":false,\"layout\":\"horizontal\",\"subEvent\":\"hover\",\"subCloseBehavior\":\"mouseleave\",\"mouseLeaveDelay\":500,\"subTrigger\":\"item\",\"subPosition\":\"right\",\"megaWidthType\":\"container\",\"megaWidthSelector\":\"\",\"breakpoint\":768,\"signatures\":{\"template_4869\":{\"id\":4869,\"signature\":\"b74684c1d02d7763c3280c0c406ab49a\"}}}'><div class=\"jet-mega-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Open\/Close Menu\"><div class=\"jet-mega-menu-toggle-icon jet-mega-menu-toggle-icon--default-state\"><i class=\"fas fa-bars\"><\/i><\/div><div class=\"jet-mega-menu-toggle-icon jet-mega-menu-toggle-icon--opened-state\"><i class=\"fas fa-times\"><\/i><\/div><\/div><nav class=\"jet-mega-menu-container\" aria-label=\"Main nav\"><ul class=\"jet-mega-menu-list\"><li id=\"jet-mega-menu-item-13145\" class=\"jet-mega-menu-item jet-mega-menu-item-type-custom jet-mega-menu-item-object-custom jet-mega-menu-item--mega jet-mega-menu-item-has-children jet-mega-menu-item--top-level jet-mega-menu-item-13145\"><div class=\"jet-mega-menu-item__inner\" role=\"button\" tabindex=\"0\" aria-haspopup=\"true\" aria-expanded=\"false\" aria-label=\"Nos marques\"><a href=\"\/fr\/#marques\" class=\"jet-mega-menu-item__link jet-mega-menu-item__link--top-level\"><div class=\"jet-mega-menu-item__title\"><div class=\"jet-mega-menu-item__label\">Nos marques<\/div><\/div><\/a><div class=\"jet-mega-menu-item__dropdown\"><i class=\"fas fa-angle-down\"><\/i><\/div><\/div><div class=\"jet-mega-menu-mega-container\" data-template-id=\"13830\" data-template-content=\"elementor\" data-position=\"default\"><div class=\"jet-mega-menu-mega-container__inner\"><style><\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13830\" class=\"elementor elementor-13830\" data-elementor-post-type=\"jet-menu\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6723523 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6723523\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-931b173\" data-id=\"931b173\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46469b6 elementor-widget elementor-widget-shortcode\" data-id=\"46469b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9860\" class=\"elementor elementor-9860 elementor-7744 elementor-7744 elementor-7744\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ece4322 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ece4322\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-55bd5390\" data-id=\"55bd5390\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42d43a9 elementor-widget elementor-widget-spacer\" data-id=\"42d43a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41753c30 elementor-widget elementor-widget-image\" data-id=\"41753c30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/radtorque\/cles-dynamometriques\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RAD-Torque-Systems-Logo.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3904827 elementor-widget elementor-widget-text-editor\" data-id=\"3904827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCl\u00e9s \u00e0 couple \u00e9lev\u00e9\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24374582 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"24374582\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/radtorque\/cles-dynamometriques\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"next\" width=\"26.827\" height=\"26.827\" viewBox=\"0 0 26.827 26.827\"><g id=\"Group_8\" data-name=\"Group 8\"><g id=\"Group_7\" data-name=\"Group 7\"><path id=\"Path_11\" data-name=\"Path 11\" d=\"M13.414,0A13.414,13.414,0,1,0,26.827,13.414,13.429,13.429,0,0,0,13.414,0Zm4.144,14.2-5.589,5.589a1.118,1.118,0,0,1-1.581-1.581l4.8-4.8-4.8-4.8a1.118,1.118,0,0,1,1.581-1.581l5.589,5.589A1.117,1.117,0,0,1,17.557,14.2Z\" fill=\"#ea0029\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voir la marque<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87ceba3 elementor-widget elementor-widget-spacer\" data-id=\"87ceba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1a89eda\" data-id=\"1a89eda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35a2e78 elementor-widget elementor-widget-spacer\" data-id=\"35a2e78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17e56bc elementor-widget elementor-widget-image\" data-id=\"17e56bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/trackwrench\/dynamometriques-manuelles\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/05\/TrackWrench_Logo_Transparent.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a4a095 elementor-widget elementor-widget-text-editor\" data-id=\"6a4a095\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCl\u00e9s manuelles digital\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e749ac elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4e749ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/trackwrench\/dynamometriques-manuelles\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"next\" width=\"26.827\" height=\"26.827\" viewBox=\"0 0 26.827 26.827\"><g id=\"Group_8\" data-name=\"Group 8\"><g id=\"Group_7\" data-name=\"Group 7\"><path id=\"Path_11\" data-name=\"Path 11\" d=\"M13.414,0A13.414,13.414,0,1,0,26.827,13.414,13.429,13.429,0,0,0,13.414,0Zm4.144,14.2-5.589,5.589a1.118,1.118,0,0,1-1.581-1.581l4.8-4.8-4.8-4.8a1.118,1.118,0,0,1,1.581-1.581l5.589,5.589A1.117,1.117,0,0,1,17.557,14.2Z\" fill=\"#ea0029\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voir la marque<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3bd3f24\" data-id=\"3bd3f24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f40942f elementor-widget elementor-widget-spacer\" data-id=\"f40942f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70072c21 elementor-widget elementor-widget-image\" data-id=\"70072c21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/modec\/cles-a-broche\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/06\/Modec-Portable-Valve-Actuators-Logo.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7570bbd1 elementor-widget elementor-widget-text-editor\" data-id=\"7570bbd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCl\u00e9s \u00e0 broche\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e33ec58 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4e33ec58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/modec\/cles-a-broche\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"next\" width=\"26.827\" height=\"26.827\" viewBox=\"0 0 26.827 26.827\"><g id=\"Group_8\" data-name=\"Group 8\"><g id=\"Group_7\" data-name=\"Group 7\"><path id=\"Path_11\" data-name=\"Path 11\" d=\"M13.414,0A13.414,13.414,0,1,0,26.827,13.414,13.429,13.429,0,0,0,13.414,0Zm4.144,14.2-5.589,5.589a1.118,1.118,0,0,1-1.581-1.581l4.8-4.8-4.8-4.8a1.118,1.118,0,0,1,1.581-1.581l5.589,5.589A1.117,1.117,0,0,1,17.557,14.2Z\" fill=\"#ea0029\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voir la marque<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-34345bdc\" data-id=\"34345bdc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a0ae58 elementor-widget elementor-widget-spacer\" data-id=\"0a0ae58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6212f7f5 elementor-widget elementor-widget-image\" data-id=\"6212f7f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/radialtorque\/produits\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/06\/RTT-Logo.svg\" title=\"\" alt=\"RTT Logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3a6d39 elementor-widget elementor-widget-text-editor\" data-id=\"b3a6d39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPersonnalisation et accessoires\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8b67de elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8b67de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/radialtorque\/produits\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"next\" width=\"26.827\" height=\"26.827\" viewBox=\"0 0 26.827 26.827\"><g id=\"Group_8\" data-name=\"Group 8\"><g id=\"Group_7\" data-name=\"Group 7\"><path id=\"Path_11\" data-name=\"Path 11\" d=\"M13.414,0A13.414,13.414,0,1,0,26.827,13.414,13.429,13.429,0,0,0,13.414,0Zm4.144,14.2-5.589,5.589a1.118,1.118,0,0,1-1.581-1.581l4.8-4.8-4.8-4.8a1.118,1.118,0,0,1,1.581-1.581l5.589,5.589A1.117,1.117,0,0,1,17.557,14.2Z\" fill=\"#ea0029\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Voir la marque<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/li>\n<li id=\"jet-mega-menu-item-13146\" class=\"jet-mega-menu-item jet-mega-menu-item-type-custom jet-mega-menu-item-object-custom jet-mega-menu-item--mega jet-mega-menu-item-has-children jet-mega-menu-item--top-level jet-mega-menu-item-13146\"><div class=\"jet-mega-menu-item__inner\" role=\"button\" tabindex=\"0\" aria-haspopup=\"true\" aria-expanded=\"false\" aria-label=\"Industries\"><a href=\"\/fr\/#industries\" class=\"jet-mega-menu-item__link jet-mega-menu-item__link--top-level\"><div class=\"jet-mega-menu-item__title\"><div class=\"jet-mega-menu-item__label\">Industries<\/div><\/div><\/a><div class=\"jet-mega-menu-item__dropdown\"><i class=\"fas fa-angle-down\"><\/i><\/div><\/div><div class=\"jet-mega-menu-mega-container\" data-template-id=\"13836\" data-template-content=\"elementor\" data-position=\"default\"><div class=\"jet-mega-menu-mega-container__inner\"><style><\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"13836\" class=\"elementor elementor-13836\" data-elementor-post-type=\"jet-menu\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38282f7 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"38282f7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c89b07b\" data-id=\"c89b07b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bcdcb1 elementor-widget elementor-widget-shortcode\" data-id=\"7bcdcb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9843\" class=\"elementor elementor-9843 elementor-7378 elementor-7378 elementor-7378\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20141858 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20141858\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-722a5c32\" data-id=\"722a5c32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2045e4d8 elementor-widget elementor-widget-spacer\" data-id=\"2045e4d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f812b02 elementor-widget elementor-widget-image\" data-id=\"2f812b02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/energie-eolienne\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/wind-turbine.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-264c20d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"264c20d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/energie-eolienne\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00c9nergie \u00e9olienne<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c993adb elementor-widget elementor-widget-spacer\" data-id=\"4c993adb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6855a641 elementor-widget elementor-widget-image\" data-id=\"6855a641\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/exploitation-miniere\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/mine-truck.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ed2da98 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ed2da98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/exploitation-miniere\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Exploitation mini\u00e8re<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94fbddf elementor-widget elementor-widget-spacer\" data-id=\"94fbddf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-26023bf0\" data-id=\"26023bf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f42f4e elementor-widget elementor-widget-spacer\" data-id=\"62f42f4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20b00566 elementor-widget elementor-widget-image\" data-id=\"20b00566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/petrole-gaz-et-petrochimie\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/oil-pump.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d9d152a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3d9d152a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/petrole-gaz-et-petrochimie\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u00e9trole &amp; Gaz et p\u00e9trochimie<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5861185 elementor-widget elementor-widget-spacer\" data-id=\"5861185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-497a0ba1 elementor-widget elementor-widget-image\" data-id=\"497a0ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/offshore\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/platform.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-667a5fea elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"667a5fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/offshore\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Offshore<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-79d5eff3\" data-id=\"79d5eff3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3471d2f7 elementor-widget elementor-widget-spacer\" data-id=\"3471d2f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61f4a38f elementor-widget elementor-widget-image\" data-id=\"61f4a38f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/construction-en-acier\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/steel-1.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-269f0a87 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"269f0a87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/construction-en-acier\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Construction en acier<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71cac794 elementor-widget elementor-widget-spacer\" data-id=\"71cac794\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a913d66 elementor-widget elementor-widget-image\" data-id=\"a913d66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/grues-a-tour\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/lift.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf09166 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4cf09166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/grues-a-tour\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Grues \u00e0 tour<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-16ecb975\" data-id=\"16ecb975\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a32264 elementor-widget elementor-widget-spacer\" data-id=\"7a32264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77820ee1 elementor-widget elementor-widget-image\" data-id=\"77820ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/travaux-publics\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/rail-road.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34e1c331 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"34e1c331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/travaux-publics\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Travaux publics<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-583d6d74 elementor-widget elementor-widget-spacer\" data-id=\"583d6d74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d56c39 elementor-widget elementor-widget-image\" data-id=\"3d56c39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/diesels-marins-construction-et-revision\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/motor.svg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea09492 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2ea09492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/diesels-marins-construction-et-revision\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" xmlns:svgjs=\"http:\/\/svgjs.com\/svgjs\" width=\"512\" height=\"512\" x=\"0\" y=\"0\" viewBox=\"0 0 6.3499999 6.3500002\" style=\"enable-background:new 0 0 512 512\" xml:space=\"preserve\" class=\"\"><g><g xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"layer1\" transform=\"translate(0 -290.65)\"><path id=\"path9429\" d=\"m2.2580394 291.96502a.26460982.26460982 0 0 0 -.1741496.46871l1.6190225 1.38699-1.6190225 1.38648a.26460982.26460982 0 1 0 .3436483.40049l1.8536335-1.58595a.26460982.26460982 0 0 0 0-.40256l-1.8536335-1.5875a.26460982.26460982 0 0 0 -.1694987-.0667z\" fill=\"#ea0029\" data-original=\"#000000\" class=\"\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Diesels marins : construction et r\u00e9vision<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/li>\n<li id=\"jet-mega-menu-item-9830\" class=\"jet-mega-menu-item jet-mega-menu-item-type-post_type jet-mega-menu-item-object-page jet-mega-menu-item--default jet-mega-menu-item--top-level jet-mega-menu-item-9830\"><div class=\"jet-mega-menu-item__inner\"><a href=\"https:\/\/www.radialtorque.eu\/fr\/location\/\" class=\"jet-mega-menu-item__link jet-mega-menu-item__link--top-level\"><div class=\"jet-mega-menu-item__title\"><div class=\"jet-mega-menu-item__label\">Location<\/div><\/div><\/a><\/div><\/li>\n<li id=\"jet-mega-menu-item-24357\" class=\"jet-mega-menu-item jet-mega-menu-item-type-post_type jet-mega-menu-item-object-page jet-mega-menu-item--default jet-mega-menu-item--top-level jet-mega-menu-item-24357\"><div class=\"jet-mega-menu-item__inner\"><a href=\"https:\/\/www.radialtorque.eu\/fr\/expositions\/\" class=\"jet-mega-menu-item__link jet-mega-menu-item__link--top-level\"><div class=\"jet-mega-menu-item__title\"><div class=\"jet-mega-menu-item__label\">Expositions<\/div><\/div><\/a><\/div><\/li>\n<li id=\"jet-mega-menu-item-41328\" class=\"jet-mega-menu-item jet-mega-menu-item-type-custom jet-mega-menu-item-object-custom jet-mega-menu-item--default jet-mega-menu-item--top-level jet-mega-menu-item-41328\"><div class=\"jet-mega-menu-item__inner\"><a href=\"\/fr\/torquetips\/\" class=\"jet-mega-menu-item__link jet-mega-menu-item__link--top-level\"><div class=\"jet-mega-menu-item__title\"><div class=\"jet-mega-menu-item__label\">Torque Tips\ud83d\udd29<\/div><\/div><\/a><\/div><\/li>\n<\/ul><\/nav><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-0344903\" data-id=\"0344903\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bd36af elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0bd36af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6ac79b\" data-id=\"b6ac79b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4c98d3 elementor-widget elementor-widget-shortcode\" data-id=\"c4c98d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"30117\" class=\"elementor elementor-30117 elementor-604 elementor-604\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57e263b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57e263b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-677c0a36\" data-id=\"677c0a36\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-430116cf elementor-widget elementor-widget-breadcrumbs\" data-id=\"430116cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.radialtorque.eu\/fr\/home\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-657325c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"657325c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad5d0bb\" data-id=\"ad5d0bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6332f97 elementor-widget elementor-widget-spacer\" data-id=\"6332f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c2ca6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c2ca6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f598112\" data-id=\"f598112\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67ccb71 elementor-widget elementor-widget-heading\" data-id=\"67ccb71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nouvelles<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d7626f\" data-id=\"1d7626f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-087bd78 elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"087bd78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-07dade2\" data-id=\"07dade2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a76a175 elementor-widget elementor-widget-spacer\" data-id=\"a76a175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0add67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0add67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-59643b2\" data-id=\"59643b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a443d04 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"a443d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;numbers_and_prev_next&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-44924 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x-4000\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"482\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/02\/B-RAD-X-4000-Nieuws-768x482.png\" class=\"attachment-medium_large size-medium_large wp-image-41107\" alt=\"B-RAD X 4000\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/02\/B-RAD-X-4000-Nieuws-768x482.png 768w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/02\/B-RAD-X-4000-Nieuws-300x188.png 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/02\/B-RAD-X-4000-Nieuws-1024x643.png 1024w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2025\/02\/B-RAD-X-4000-Nieuws.png 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x-4000\/\" >\n\t\t\t\tNOUVEAU: B-RAD X 4000\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>RAD Torque, leader du march\u00e9 dans la production de cl\u00e9s dynamom\u00e9triques industrielles, a ajout\u00e9 la B-RAD X 4000 \u00e0 sa s\u00e9rie renomm\u00e9e de cl\u00e9s dynamom\u00e9triques<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x-4000\/\" aria-label=\"En savoir plus sur NOUVEAU: B-RAD X 4000\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 f\u00e9vrier 2025\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-39547 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-mobile-calibration-system\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-38832\" alt=\"Mobile Calibration System\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws-768x432.jpg 768w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws-300x169.jpg 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws-1024x576.jpg 1024w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws-1536x864.jpg 1536w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/12\/Mobile-Calibration-Systems-Nieuws.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-mobile-calibration-system\/\" >\n\t\t\t\tNOUVEAU : Mobile Calibration System\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Pour les cl\u00e9s dynamom\u00e9triques de plus grande capacit\u00e9, le RTT peut fournir le Mobile Calibration System. Ce syst\u00e8me de calibration mobile utilise des boulons M72<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-mobile-calibration-system\/\" aria-label=\"En savoir plus sur NOUVEAU : Mobile Calibration System\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t20 d\u00e9cembre 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-36423 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-sdm-battery\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/09\/SDM-Battery-680P-Application.png\" class=\"attachment-medium_large size-medium_large wp-image-36468\" alt=\"SDM Battery 680P\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/09\/SDM-Battery-680P-Application.png 650w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/09\/SDM-Battery-680P-Application-300x300.png 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/09\/SDM-Battery-680P-Application-150x150.png 150w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-sdm-battery\/\" >\n\t\t\t\tNOUVEAU : SDM Battery\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Petit par la taille, immense par les performances \u00c0 l\u2019origine, RAD a con\u00e7u les engrenages SDM (Small Diameter Multiplier) pour l\u2019industrie a\u00e9rospatiale o\u00f9 l\u2019acc\u00e8s aux<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-sdm-battery\/\" aria-label=\"En savoir plus sur NOUVEAU : SDM Battery\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t17 septembre 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-32151 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-large-calibration-systems\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-32116\" alt=\"RAD Large Calibration Systems\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail-768x432.jpg 768w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail-300x169.jpg 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail-1024x576.jpg 1024w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail-1536x864.jpg 1536w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2024\/05\/RAD-Large-Calibration-Systems-News-Thumbnail.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-large-calibration-systems\/\" >\n\t\t\t\tNOUVEAU: LARGE CALIBRATION SYSTEMS\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>La solution pour calibrer les cl\u00e9s dynamom\u00e9triques jusqu&rsquo;\u00e0 24 400 Nm ! La pr\u00e9cision et la r\u00e9p\u00e9tabilit\u00e9 des syst\u00e8mes d&rsquo;\u00e9talonnage RAD leur ont valu une<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-large-calibration-systems\/\" aria-label=\"En savoir plus sur NOUVEAU: LARGE CALIBRATION SYSTEMS\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 mai 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24418 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-15004\" alt=\"B-RAD X video\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail-768x432.jpg 768w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail-300x169.jpg 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail-1024x576.jpg 1024w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail-1536x864.jpg 1536w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/11\/B-RAD-X-Thumbnail.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x\/\" >\n\t\t\t\tNOUVEAU : B-RAD X\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>S&rsquo;appuyant sur des ann\u00e9es d&rsquo;exp\u00e9rience dans le d\u00e9veloppement de cl\u00e9s dynamom\u00e9triques multiplicatrices, RAD Torque annonce la cl\u00e9 dynamom\u00e9trique sans fil la plus puissante du march\u00e9<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/nouveau-b-rad-x\/\" aria-label=\"En savoir plus sur NOUVEAU : B-RAD X\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t2 juin 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-24409 post type-post status-publish format-standard has-post-thumbnail hentry category-nouvelles\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/batterie-haute-performance-lihd-80-ah\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/industrieen_optioneel_8.0_accu.jpg-768x768.jpg\" class=\"attachment-medium_large size-medium_large wp-image-11333\" alt=\"Batteries 8,0\" srcset=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/industrieen_optioneel_8.0_accu.jpg-768x768.jpg 768w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/industrieen_optioneel_8.0_accu.jpg-300x300.jpg 300w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/industrieen_optioneel_8.0_accu.jpg.jpg 1024w, https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/09\/industrieen_optioneel_8.0_accu.jpg-150x150.jpg 150w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Nouvelles<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/batterie-haute-performance-lihd-80-ah\/\" >\n\t\t\t\tBatterie haute performance LiHD 8,0 Ah\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Les nouvelles cellules de batterie de haute qualit\u00e9 et les composants \u00e9lectroniques enti\u00e8rement nouveaux garantissent une dur\u00e9e de vie de la batterie encore plus longue<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-post__read-more-wrapper\">\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.radialtorque.eu\/fr\/nouvelles\/batterie-haute-performance-lihd-80-ah\/\" aria-label=\"En savoir plus sur Batterie haute performance LiHD 8,0 Ah\" tabindex=\"-1\" >\n\t\t\tLire la suite\t\t<\/a>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t7 octobre 2022\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"2\" data-next-page=\"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425\/page\/2\/\"><\/div>\n\t\t\t\t<nav class=\"elementor-pagination\" aria-label=\"Pagination\">\n\t\t\t<span class=\"page-numbers prev\">\u00ab Pr\u00e9c\u00e9dent<\/span>\n<span aria-current=\"page\" class=\"page-numbers current\"><span class=\"elementor-screen-only\">Page<\/span>1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425\/page\/2\/\"><span class=\"elementor-screen-only\">Page<\/span>2<\/a>\n<a class=\"page-numbers next\" href=\"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425\/page\/2\/\">Suivant \u00bb<\/a>\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6de44f elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6de44f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b4208d\" data-id=\"4b4208d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d1609e elementor-widget elementor-widget-spacer\" data-id=\"0d1609e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Onze merken Hoog momentsleutels Bekijk merk Digitale hand momentsleutels Bekijk merk Spindelsleutels Bekijk merk Maatwerk en accessoires Bekijk merk Industrie\u00ebn Windenergie Mijnbouw Olie &amp; Gas en petrochemie Offshore Staalbouw Torenkranen Civiele techniek Scheepsdiesels, bouw en revisie Verhuur Beurzen Vacatures (2) Torque Tips\ud83d\udd29 Nouvelles<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"wf_page_folders":[8],"class_list":["post-9425","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvelles - Radial Torque Tools<\/title>\n<meta name=\"description\" content=\"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d&#039;informations sur les outils dynamom\u00e9triques radiaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radialtorque.eu\/fr\/actus\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvelles - Radial Torque Tools\" \/>\n<meta property=\"og:description\" content=\"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d&#039;informations sur les outils dynamom\u00e9triques radiaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radialtorque.eu\/fr\/actus\/\" \/>\n<meta property=\"og:site_name\" content=\"Radial Torque Tools B.V.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T12:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RadMomentsleutels_Web.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/\",\"name\":\"Nouvelles - Radial Torque Tools\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RAD-Torque-Systems-Logo.png\",\"datePublished\":\"2022-05-12T13:25:48+00:00\",\"dateModified\":\"2026-04-28T12:09:28+00:00\",\"description\":\"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d'informations sur les outils dynamom\u00e9triques radiaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RAD-Torque-Systems-Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RAD-Torque-Systems-Logo.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/actus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/\",\"name\":\"Radial Torque Tools B.V.\",\"description\":\"Radial Torque Tools B.V.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#organization\",\"name\":\"Radial Torque Tools B.V.\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/RADIAL_Logo__DEF.svg\",\"contentUrl\":\"https:\\\/\\\/www.radialtorque.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/RADIAL_Logo__DEF.svg\",\"width\":786,\"height\":208,\"caption\":\"Radial Torque Tools B.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.radialtorque.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvelles - Radial Torque Tools","description":"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d'informations sur les outils dynamom\u00e9triques radiaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radialtorque.eu\/fr\/actus\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvelles - Radial Torque Tools","og_description":"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d'informations sur les outils dynamom\u00e9triques radiaux.","og_url":"https:\/\/www.radialtorque.eu\/fr\/actus\/","og_site_name":"Radial Torque Tools B.V.","article_modified_time":"2026-04-28T12:09:28+00:00","og_image":[{"url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RadMomentsleutels_Web.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/","url":"https:\/\/www.radialtorque.eu\/fr\/actus\/","name":"Nouvelles - Radial Torque Tools","isPartOf":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/#primaryimage"},"image":{"@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RAD-Torque-Systems-Logo.png","datePublished":"2022-05-12T13:25:48+00:00","dateModified":"2026-04-28T12:09:28+00:00","description":"Consultez les derni\u00e8res nouvelles sur les batteries, les cl\u00e9s dynamom\u00e9triques, les accessoires et plus d'informations sur les outils dynamom\u00e9triques radiaux.","breadcrumb":{"@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radialtorque.eu\/fr\/actus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/#primaryimage","url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RAD-Torque-Systems-Logo.png","contentUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/03\/RAD-Torque-Systems-Logo.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.radialtorque.eu\/fr\/actus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.radialtorque.eu\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Nouvelles"}]},{"@type":"WebSite","@id":"https:\/\/www.radialtorque.eu\/fr\/#website","url":"https:\/\/www.radialtorque.eu\/fr\/","name":"Radial Torque Tools B.V.","description":"Radial Torque Tools B.V.","publisher":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radialtorque.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.radialtorque.eu\/fr\/#organization","name":"Radial Torque Tools B.V.","url":"https:\/\/www.radialtorque.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.radialtorque.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/02\/RADIAL_Logo__DEF.svg","contentUrl":"https:\/\/www.radialtorque.eu\/wp-content\/uploads\/2022\/02\/RADIAL_Logo__DEF.svg","width":786,"height":208,"caption":"Radial Torque Tools B.V."},"image":{"@id":"https:\/\/www.radialtorque.eu\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/comments?post=9425"}],"version-history":[{"count":10,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425\/revisions"}],"predecessor-version":[{"id":45478,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/pages\/9425\/revisions\/45478"}],"wp:attachment":[{"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/media?parent=9425"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/www.radialtorque.eu\/fr\/wp-json\/wp\/v2\/wf_page_folders?post=9425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}